{"id":91504,"date":"2018-11-10T18:21:53","date_gmt":"2025-01-14T09:12:00","guid":{"rendered":"https:\/\/www.light-style.eu\/unser-foto-shop\/koenigssee-2017-115\/"},"modified":"2025-01-14T10:12:00","modified_gmt":"2025-01-14T09:12:00","slug":"koenigssee-2017-115","status":"publish","type":"product","link":"https:\/\/www.light-style.eu\/es\/nuestra-tienda-de-fotograf\u00eda\/koenigssee-2017-115\/","title":{"rendered":"K\u00f6nigssee 2017-115"},"content":{"rendered":"<p>Nuestro K\u00f6nigsee alem\u00e1n, un paisaje como sacado de un libro de cuentos de hadas. Puedes entender c\u00f3mo surgi\u00f3 este nombre. Aqu\u00ed est\u00e1n los cobertizos para botes para los amantes del SW <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Todos nuestros cuadros en acr\u00edlico y lienzo est\u00e1n firmados a mano por el artista y vienen con un certificado de autenticidad<\/p>\n","protected":false},"featured_media":78056,"template":"","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","ngg_post_thumbnail":0,"jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"product_brand":[],"product_cat":[2150,2153,2147,2033,2034],"product_tag":[2214,2285,2322,2274],"class_list":["post-91504","product","type-product","status-publish","has-post-thumbnail","product_cat-alemania","product_cat-edificios","product_cat-naturaleza","product_cat-paises","product_cat-todo","product_tag-alemania","product_tag-europa-es","product_tag-koenigsee-es","product_tag-paises","pa_wandbilder-foto-seda-mate-20x30cm","pa_wandbilder-lienzo-20x30","pa_wandbilder-lienzo-40x60","pa_wandbilder-lienzo-60x90","pa_wandbilder-lienzo-80-x-120-cm","pa_wandbilder-pintura-acrilica-20x30","pa_wandbilder-pintura-acrilica-40x60","pa_wandbilder-pintura-acrilica-60x90","pa_wandbilder-poster-acabado-satinado-40x60-cm","pa_wandbilder-poster-semibrillante-30x45cm","pa_wandbilder-poster-semibrillante-60x90cm","pa_wandbilder-poster-semibrillante-70x105cm","entry","has-media","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"jetpack_publicize_connections":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.light-style.eu\/es\/wp-json\/wp\/v2\/product\/91504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.light-style.eu\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.light-style.eu\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.light-style.eu\/es\/wp-json\/wp\/v2\/media\/78056"}],"wp:attachment":[{"href":"https:\/\/www.light-style.eu\/es\/wp-json\/wp\/v2\/media?parent=91504"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.light-style.eu\/es\/wp-json\/wp\/v2\/product_brand?post=91504"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.light-style.eu\/es\/wp-json\/wp\/v2\/product_cat?post=91504"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.light-style.eu\/es\/wp-json\/wp\/v2\/product_tag?post=91504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}